{"id":1432,"date":"2023-12-29T10:15:55","date_gmt":"2023-12-29T10:15:55","guid":{"rendered":"https:\/\/www.apexglobalsolutionsme.com\/kuwait\/kuwait\/?post_type=product&#038;p=1432"},"modified":"2024-01-04T10:37:58","modified_gmt":"2024-01-04T10:37:58","slug":"siemens-1fl6032-synchronous-ac-motor-200-w-230-v-flange-mount-mounting","status":"publish","type":"product","link":"https:\/\/www.apexglobalsolutionsme.com\/kuwait\/product\/siemens-1fl6032-synchronous-ac-motor-200-w-230-v-flange-mount-mounting\/","title":{"rendered":"Siemens 1FL6032 Synchronous AC Motor, 200 W, 230 V, Flange Mount Mounting"},"content":{"rendered":"<div class=\"card-component-module_card-component__1NA2E product-detail-page-component_specifications__3iRNq card-component-module_padding__51wm7 card-component-module_white__2avgM\">\n<p class=\"card-component-module_title__bVV1D \">Specifications<\/p>\n<div class=\"product-detail-page-component_spec-list__r_evK product-detail-page-component_truncated__21db6\">\n<div class=\"product-detail-page-component_spec__2he5t\">\n<p class=\"snippet product-detail-page-component_label__3S-Gu\">Brand<\/p>\n<p class=\"snippet product-detail-page-component_value__2ZiIc\">Siemens<\/p>\n<\/div>\n<div class=\"product-detail-page-component_spec__2he5t\">\n<p class=\"snippet product-detail-page-component_label__3S-Gu\">Power Rating<\/p>\n<p class=\"snippet product-detail-page-component_value__2ZiIc\">200 W<\/p>\n<\/div>\n<div class=\"product-detail-page-component_spec__2he5t\">\n<p class=\"snippet product-detail-page-component_label__3S-Gu\">AC Motor Type<\/p>\n<p class=\"snippet product-detail-page-component_value__2ZiIc\">Synchronous<\/p>\n<\/div>\n<div class=\"product-detail-page-component_spec__2he5t\">\n<p class=\"snippet product-detail-page-component_label__3S-Gu\">Supply Voltage<\/p>\n<p class=\"snippet product-detail-page-component_value__2ZiIc\">230 V<\/p>\n<\/div>\n<div class=\"product-detail-page-component_spec__2he5t\">\n<p class=\"snippet product-detail-page-component_label__3S-Gu\">Mounting Type<\/p>\n<p class=\"snippet product-detail-page-component_value__2ZiIc\">Flange Mount<\/p>\n<\/div>\n<div class=\"product-detail-page-component_spec__2he5t\">\n<p class=\"snippet product-detail-page-component_label__3S-Gu\">Series<\/p>\n<p class=\"snippet product-detail-page-component_value__2ZiIc\">1FL6032<\/p>\n<\/div>\n<div class=\"product-detail-page-component_spec__2he5t\">\n<p class=\"snippet product-detail-page-component_label__3S-Gu\">Country of Origin<\/p>\n<p class=\"snippet product-detail-page-component_value__2ZiIc\">CN<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Specifications Brand Siemens Power Rating 200 W AC Motor Type Synchronous Supply Voltage 230 V Mounting Type Flange Mount Series 1FL6032 Country of Origin CN<\/p>\n","protected":false},"featured_media":1433,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[161,35],"product_tag":[],"class_list":{"0":"post-1432","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-siemens-electric-motors","7":"product_cat-siemens","8":"entry","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"product-type-simple","15":"add-to-wishlist-after_add_to_cart"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.apexglobalsolutionsme.com\/kuwait\/wp-json\/wp\/v2\/product\/1432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apexglobalsolutionsme.com\/kuwait\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.apexglobalsolutionsme.com\/kuwait\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.apexglobalsolutionsme.com\/kuwait\/wp-json\/wp\/v2\/media\/1433"}],"wp:attachment":[{"href":"https:\/\/www.apexglobalsolutionsme.com\/kuwait\/wp-json\/wp\/v2\/media?parent=1432"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.apexglobalsolutionsme.com\/kuwait\/wp-json\/wp\/v2\/product_brand?post=1432"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.apexglobalsolutionsme.com\/kuwait\/wp-json\/wp\/v2\/product_cat?post=1432"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.apexglobalsolutionsme.com\/kuwait\/wp-json\/wp\/v2\/product_tag?post=1432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}